{"id":4941,"date":"2026-03-19T10:00:00","date_gmt":"2026-03-19T09:00:00","guid":{"rendered":"https:\/\/www.horlyviaggi.it\/viaggi\/?page_id=4941"},"modified":"2026-05-03T23:45:34","modified_gmt":"2026-05-03T21:45:34","slug":"estate-in-cilento","status":"publish","type":"page","link":"https:\/\/www.horlyviaggi.it\/viaggi\/estate-in-cilento\/","title":{"rendered":"Estate 2026 in Cilento"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-adbeb591 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-info-box uagb-block-ea1e98f0 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\"><strong>Estate 2026 IN Cilento <\/strong><\/p><\/div><div class=\"uagb-ifb-separator\"><\/div><p class=\"uagb-ifb-desc\">Scopri le nostre prossime <strong>Vacanze e Viaggi di Gruppo<\/strong> per l&#8217;<strong>Estate 2026 in Campania<\/strong> nel fantastico <strong>Cilento<\/strong> dal <strong>2 al 30 agosto 2026<\/strong>.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-87b1688c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-4c9e5cab uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Viaggiare, conoscere ed emozionarsi in Campania<\/h3><\/div><p class=\"uagb-ifb-desc\">Per l&#8217;<strong>Estate 2026 Horly Viaggi<\/strong> vuole portare i suoi ospiti a vivere una fantastica vacanza nel meraviglioso <strong>Cilento <\/strong>in<strong> Campania<\/strong>.<\/p><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5485eaf5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b9a376e9\"><h3 class=\"uagb-heading-text\">Agosto 2026<\/h3><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-4d73810f wp-block-group-is-layout-grid\"><div class=\"wp-block-uagb-loop-builder uagb-block-ce8e7994      alignwide\" data-block_id=\"ce8e7994\"  style=\"\">\n<div class=\"wp-block-uagb-container uagb-block-bf8027fe alignfull uagb-is-root-container\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-5f377dc0     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-319b90fd\">\n<div class=\"wp-block-uagb-image uagb-block-03239280 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"\" width=\"1200\" height=\"800\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9c4a6211\"><p class=\"uagb-heading-text\">Mare Italia <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8a34de35\"><p class=\"uagb-heading-text\">Prenotaprima -250\u20ac <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f65e2216\"><p class=\"uagb-heading-text\">Settimana in Cilento <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5d324313\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" class=\"uag-pro-dynamic-content\">Dal 2 al 9 agosto 2026 (8gg\/7nt)<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-ef45d073\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-6b122c8e wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">SCOPRI<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"wp-block-uagb-loop-builder uagb-block-a8550462      alignwide\" data-block_id=\"a8550462\"  style=\"\">\n<div class=\"wp-block-uagb-container uagb-block-c7749bd8 alignfull uagb-is-root-container\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-70fdad5f     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-87120db6\">\n<div class=\"wp-block-uagb-image uagb-block-c83684c0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"\" width=\"1200\" height=\"800\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c273a7f6\"><p class=\"uagb-heading-text\">Mare Italia <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c83511e9\"><p class=\"uagb-heading-text\">Prenotaprima -250\u20ac <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f108d890\"><p class=\"uagb-heading-text\">Ferragosto in Cilento <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5c384f01\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" class=\"uag-pro-dynamic-content\">Dal 9 al 16 agosto 2026 (8gg\/7nt)<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7b98e2d8\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-82a7c7d0 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">SCOPRI<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"wp-block-uagb-loop-builder uagb-block-8755ad5d      alignwide\" data-block_id=\"8755ad5d\"  style=\"\">\n<div class=\"wp-block-uagb-container uagb-block-4feed63b alignfull uagb-is-root-container\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-24f82c6e     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-e3c8740a\">\n<div class=\"wp-block-uagb-image uagb-block-a8c24aea wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"\" width=\"1200\" height=\"800\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-50c94fe3\"><p class=\"uagb-heading-text\">mare italia <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6e8af511\"><p class=\"uagb-heading-text\">Prenotaprima -250\u20ac <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0f972975\"><p class=\"uagb-heading-text\">Settimana in Cilento <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-86c1af60\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" class=\"uag-pro-dynamic-content\">Dal 16al 23 agosto 2026 (8gg\/7nt)<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-e34e939f\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-daacf913 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">SCOPRI<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"wp-block-uagb-loop-builder uagb-block-e9595c3a      alignwide\" data-block_id=\"e9595c3a\"  style=\"\">\n<div class=\"wp-block-uagb-container uagb-block-bbd51cf9 alignfull uagb-is-root-container\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-0f51fa3f     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-55629b35\">\n<div class=\"wp-block-uagb-image uagb-block-42779a31 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\"  sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/plugins\/spectra-pro\/assets\/images\/placeholder.png\" alt=\"\" width=\"1200\" height=\"800\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5f89b45a\"><p class=\"uagb-heading-text\">mare italia <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5c5faaf8\"><p class=\"uagb-heading-text\">Prenotaprima -250\u20ac <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ae112029\"><p class=\"uagb-heading-text\">Settimana in Cilento <\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-beb87446\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" class=\"uag-pro-dynamic-content\">Dal 23 al 30 agosto 2026 (8gg\/7nt)<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7685bf4e\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-ab0e37e7 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">SCOPRI<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-5d51cf7e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-7482085c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Pronto a Partire con Noi?<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Non perdere l&#8217;opportunit\u00e0 di vivere un&#8217;esperienza di viaggio unica con <strong>Horly Viaggi<\/strong>. I nostri accompagnatori esperti ti aspettano per guidarti alla scoperta delle meraviglie d&#8217;Italia.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/www.horlyviaggi.it\/viaggi\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">SCOPRI TUTTE LE VACANZE<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9d11e51c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-6f407804\">\n<div class=\"wp-block-uagb-image uagb-block-716f4730 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2024\/07\/cropped-horly-icon-min-200x200.png ,https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2024\/07\/cropped-horly-icon-min.png 780w, https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2024\/07\/cropped-horly-icon-min.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2024\/07\/cropped-horly-icon-min-200x200.png\" alt=\"Horly Viaggi - Viaggi di Gruppo - Icona\" class=\"uag-image-331\" width=\"120\" height=\"120\" title=\"Horly Viaggi - Viaggi di Gruppo - Icona\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2aa54d97\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-9a935cfd wp-block-button\"><div class=\"uagb-cta__wrap\"><h3 class=\"uagb-cta__title\"><strong>Newsletter<\/strong><\/h3><p class=\"uagb-cta__desc\"><strong>Iscriviti gratuitamente<\/strong> alla nostra <strong>Newsletter<\/strong> per essere sempre aggiornato sulle <strong>Nuove Offerte<\/strong> e sulle <strong>Prossime Vacanze e Viaggi di Gruppo<\/strong>.<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/www.horlyviaggi.it\/viaggi\/newsletter\/\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\">ISCRIVITI<\/a><\/div><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Agosto 2026<\/p>\n","protected":false},"author":1,"featured_media":4804,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4941","page","type-page","status-publish","has-post-thumbnail","hentry"],"spectra_custom_meta":{"_edit_lock":["1777844735:1"],"rank_math_seo_score":["68"],"rank_math_internal_links_processed":["1"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"ast-disable-related-posts":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["1"],"cmplz_hide_cookiebanner":[""],"rank_math_title":["Estate 2026 in Cilento | Vacanze e Viaggi di Gruppo | Horly Viaggi"],"rank_math_description":["Per l'Estate 2026 in Cilento in Campania, dal 2 al 30 agosto 2026 Horly Viaggi vi dar\u00e0 la possibilit\u00e0 di scegliere in quali settimane fare la vostra vacanza."],"rank_math_focus_keyword":["Estate 2026 in Cilento"],"_thumbnail_id":["4804"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:17;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:4;s:18:\"uagb\/buttons-child\";i:4;s:19:\"uagb\/call-to-action\";i:1;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:15;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:5;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:3;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:4;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:4;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776780470"],"_uag_css_file_name":["uag-css-4941.css"],"_uag_js_file_name":["uag-js-4941.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:156922:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}.wp-block-uagb-container.uagb-block-adbeb591 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-adbeb591 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-adbeb591 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-adbeb591 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-adbeb591 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-adbeb591{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-adbeb591{min-height: 250px;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(90deg,rgb(4,50,99) 0%,rgb(35,158,254) 100%);;background-clip: padding-box;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-ea1e98f0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-ea1e98f0 .uagb-ifb-icon svg{fill: #333;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ea1e98f0 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ea1e98f0 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ea1e98f0 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ea1e98f0 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-5);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ea1e98f0.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ea1e98f0.wp-block-uagb-info-box .uagb-ifb-desc{color: #fefefe;margin-bottom: 20px;}.uagb-block-ea1e98f0 .uagb-ifb-separator{width: 15%;border-top-width: 3px;border-top-color: #e50000;border-top-style: solid;margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ea1e98f0 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 15%;border-top-width: 3px;border-top-color: #e50000;border-top-style: solid;}.uagb-block-ea1e98f0 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ea1e98f0 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ea1e98f0 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-ea1e98f0.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ea1e98f0 .uagb-ifb-title{text-transform: uppercase;font-size: 35px;letter-spacing: 1px;}.uagb-block-ea1e98f0 .uagb-ifb-title-prefix{font-family: \"Montserrat\";font-weight: 500;font-size: 20px;}[dir=rtl] .uagb-block-ea1e98f0 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-87b1688c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87b1688c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87b1688c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87b1688c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87b1688c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87b1688c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87b1688c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-87b1688c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-4c9e5cab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-4c9e5cab .uagb-ifb-icon svg{fill: #333;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4c9e5cab .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4c9e5cab .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4c9e5cab .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4c9e5cab .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4c9e5cab.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-4c9e5cab.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-4c9e5cab .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4c9e5cab .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4c9e5cab .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4c9e5cab .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4c9e5cab .uagb-infobox__content-wrap{text-align: center;}.uagb-block-4c9e5cab.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-bottom: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-bottom: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4c9e5cab .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5485eaf5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5485eaf5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5485eaf5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5485eaf5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5485eaf5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5485eaf5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5485eaf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5485eaf5{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-b9a376e9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b9a376e9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b9a376e9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b9a376e9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-bf8027fe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf8027fe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf8027fe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf8027fe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf8027fe .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8027fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-bf8027fe{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 24px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-5f377dc0.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-5f377dc0.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-319b90fd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-319b90fd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-319b90fd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-319b90fd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-319b90fd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-319b90fd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-319b90fd{box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-319b90fd:hover{box-shadow: 0px 4px 12px 0px  ;}.uagb-block-03239280.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-03239280.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-03239280.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: px;height: auto;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(33,127,146) 0%,rgb(74,225,255) 100%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(128,0,48) 0%,rgb(255,69,177) 96%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading {text-align: center;padding-top: 16px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216 .uagb-heading-text{text-decoration: none;font-weight: 800;font-size: 23px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-5d324313.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 0px;padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-5d324313.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5d324313.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d324313.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d324313.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d324313 .uagb-heading-text{font-size: 15px;}.uagb-block-ef45d073.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-ef45d073.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-ef45d073 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-ef45d073 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-ef45d073 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-ef45d073 .uagb-button__wrapper{margin-top: 24px;margin-bottom: 24px;margin-left: 24px;margin-right: 24px;}.wp-block-uagb-buttons .uagb-block-6b122c8e.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .wp-block-button__link:hover{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .wp-block-button__link:focus{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-button__wrapper .uagb-buttons-repeater{font-weight: 800;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-6b122c8e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);font-weight: 800;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-button__link{text-transform: normal;text-decoration: none;font-weight: 800;}.wp-block-uagb-container.uagb-block-c7749bd8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7749bd8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7749bd8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7749bd8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7749bd8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7749bd8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c7749bd8{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 24px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-70fdad5f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-70fdad5f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-87120db6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87120db6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87120db6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-87120db6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-87120db6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87120db6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-87120db6{box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-87120db6:hover{box-shadow: 0px 4px 12px 0px  ;}.uagb-block-c83684c0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-c83684c0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c83684c0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: px;height: auto;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(33,127,146) 0%,rgb(74,225,255) 100%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(128,0,48) 0%,rgb(255,69,177) 96%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading {text-align: center;padding-top: 16px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f108d890.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f108d890 .uagb-heading-text{text-decoration: none;font-weight: 800;font-size: 23px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 0px;padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c384f01 .uagb-heading-text{font-size: 15px;}.uagb-block-7b98e2d8.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-7b98e2d8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7b98e2d8 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7b98e2d8 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7b98e2d8 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7b98e2d8 .uagb-button__wrapper{margin-top: 24px;margin-bottom: 24px;margin-left: 24px;margin-right: 24px;}.wp-block-uagb-buttons .uagb-block-82a7c7d0.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .wp-block-button__link:hover{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .wp-block-button__link:focus{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-button__wrapper .uagb-buttons-repeater{font-weight: 800;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-82a7c7d0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);font-weight: 800;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-button__link{text-transform: normal;text-decoration: none;font-weight: 800;}.wp-block-uagb-container.uagb-block-4feed63b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4feed63b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4feed63b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4feed63b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4feed63b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4feed63b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-4feed63b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 24px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-24f82c6e.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-24f82c6e.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-e3c8740a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3c8740a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3c8740a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3c8740a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3c8740a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3c8740a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e3c8740a{box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e3c8740a:hover{box-shadow: 0px 4px 12px 0px  ;}.uagb-block-a8c24aea.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a8c24aea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: px;height: auto;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(33,127,146) 0%,rgb(74,225,255) 100%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(128,0,48) 0%,rgb(255,69,177) 96%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading {text-align: center;padding-top: 16px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0f972975.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0f972975 .uagb-heading-text{text-decoration: none;font-weight: 800;font-size: 23px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 0px;padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86c1af60 .uagb-heading-text{font-size: 15px;}.uagb-block-e34e939f.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-e34e939f.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-e34e939f .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-e34e939f .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-e34e939f .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-e34e939f .uagb-button__wrapper{margin-top: 24px;margin-bottom: 24px;margin-left: 24px;margin-right: 24px;}.wp-block-uagb-buttons .uagb-block-daacf913.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .wp-block-button__link:hover{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .wp-block-button__link:focus{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-button__wrapper .uagb-buttons-repeater{font-weight: 800;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-daacf913.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);font-weight: 800;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-button__link{text-transform: normal;text-decoration: none;font-weight: 800;}.wp-block-uagb-container.uagb-block-bbd51cf9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bbd51cf9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bbd51cf9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bbd51cf9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bbd51cf9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbd51cf9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-bbd51cf9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 24px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-0f51fa3f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-0f51fa3f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-block-55629b35 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-55629b35 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-55629b35 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-55629b35 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-55629b35 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-55629b35{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-55629b35{box-shadow: 3px 8px 12px 0px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 3px;border-bottom-width: 3px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-55629b35:hover{box-shadow: 0px 4px 12px 0px  ;}.uagb-block-42779a31.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-42779a31.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-42779a31.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: px;height: auto;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(33,127,146) 0%,rgb(74,225,255) 100%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading {background: linear-gradient(135deg,rgb(128,0,48) 0%,rgb(255,69,177) 96%);text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 8px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8 .uagb-heading-text{text-transform: uppercase;text-decoration: none;font-weight: 600;font-size: 18px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading {text-align: center;padding-top: 16px;padding-right: 15px;padding-bottom: 8px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-alternate-background);}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading a:hover{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ae112029.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ae112029 .uagb-heading-text{text-decoration: none;font-weight: 800;font-size: 23px;line-height: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-beb87446.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 0px;padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-beb87446.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-beb87446.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-beb87446.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-beb87446.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-beb87446 .uagb-heading-text{font-size: 15px;}.uagb-block-7685bf4e.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-7685bf4e.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7685bf4e .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7685bf4e .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7685bf4e .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 12px;padding-bottom: 12px;padding-left: 30px;padding-right: 30px;}.uagb-block-7685bf4e .uagb-button__wrapper{margin-top: 24px;margin-bottom: 24px;margin-left: 24px;margin-right: 24px;}.wp-block-uagb-buttons .uagb-block-ab0e37e7.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .wp-block-button__link:hover{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .wp-block-button__link:focus{background: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-button__wrapper .uagb-buttons-repeater{font-weight: 800;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);border-style: solid;}.wp-block-uagb-buttons .uagb-block-ab0e37e7.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);font-weight: 800;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-button__link{text-transform: normal;text-decoration: none;font-weight: 800;}.wp-block-uagb-container.uagb-block-5d51cf7e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5d51cf7e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5d51cf7e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5d51cf7e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5d51cf7e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d51cf7e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d51cf7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5d51cf7e{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-7482085c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7482085c .uagb-ifb-icon svg{fill: #333;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7482085c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7482085c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7482085c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7482085c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7482085c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-7482085c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 15px;}.uagb-block-7482085c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7482085c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7482085c .uagb-ifb-align-icon-after{margin-left: 12px;}.uagb-block-7482085c .uagb-ifb-align-icon-before{margin-right: 12px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7482085c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-7482085c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7482085c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 20px;padding-left: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 20px;padding-left: 0px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-7482085c.wp-block-uagb-info-box .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);}.uagb-block-7482085c.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: var(--ast-global-color-5);background-color: var(--ast-global-color-1);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-8);border-style: solid;}.uagb-block-7482085c .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: var(--ast-global-color-5);}.uagb-block-7482085c.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:hover{color: var(--ast-global-color-1);background-color: transparent;border-color: var(--ast-global-color-1);}.uagb-block-7482085c .uagb-infobox-cta-link:hover{border-color: var(--ast-global-color-1);}.uagb-block-7482085c .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link:hover > svg{fill: var(--ast-global-color-1);}.uagb-block-7482085c.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:focus{color: var(--ast-global-color-1);background-color: transparent;border-color: var(--ast-global-color-1);}.uagb-block-7482085c .uagb-infobox-cta-link:focus{border-color: var(--ast-global-color-1);}.uagb-block-7482085c .uagb-infobox-cta-link{font-weight: 600;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-8);border-style: solid;}[dir=rtl] .uagb-block-7482085c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-7482085c.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-9d11e51c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d11e51c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d11e51c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d11e51c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d11e51c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d11e51c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d11e51c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9d11e51c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(0deg, #06558a 0%, #0063A1 100%);;background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6f407804 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f407804 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f407804 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6f407804 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6f407804 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f407804{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f407804 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6f407804{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-716f4730.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 120px;height: 120px;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-716f4730.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-716f4730.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-2aa54d97 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2aa54d97 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2aa54d97 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2aa54d97 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2aa54d97 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2aa54d97{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2aa54d97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2aa54d97{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action .uagb-cta__title{color: #ffffff;margin-bottom: 10px;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action .uagb-cta__desc{color: #ffffff;margin-bottom: 10px;}.uagb-block-9a935cfd .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-9a935cfd .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-9a935cfd .uagb-cta__content-wrap{text-align: left;}.uagb-block-9a935cfd .uagb-cta__wrap{width: 70%;text-align: left;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action{text-align: left;}.uagb-block-9a935cfd .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-9a935cfd .uagb-cta__buttons{column-gap: 15px;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-9a935cfd .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}.uagb-block-9a935cfd .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-9a935cfd .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #333;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: #ffffff;border-style: solid;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 10px;border-top-right-radius: 10px;border-bottom-left-radius: 10px;border-bottom-right-radius: 10px;border-color: #ffffff;border-style: solid;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{text-transform: uppercase;font-weight: 800;}.uagb-block-9a935cfd .uagb-cta__button-wrapper a.uagb-cta__button-link-wrapper{text-transform: uppercase;font-weight: 800;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-adbeb591{width: 100%;}.wp-block-uagb-container.uagb-block-adbeb591{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(90deg,rgb(4,50,99) 0%,rgb(35,158,254) 100%);;background-clip: padding-box;align-items: stretch;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ea1e98f0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ea1e98f0 .uagb-ifb-title{font-size: 28px;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87b1688c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87b1688c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-87b1688c{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4c9e5cab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5485eaf5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5485eaf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5485eaf5{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-b9a376e9.wp-block-uagb-advanced-heading {padding-left: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8027fe{width: 100%;}.wp-block-uagb-container.uagb-block-bf8027fe{padding-top: 0px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-5f377dc0.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-5f377dc0.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-319b90fd{width: 100%;}.wp-block-uagb-container.uagb-block-319b90fd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216 .uagb-heading-text{font-size: 19px;}.uagb-block-ef45d073.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-ef45d073.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-ef45d073 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.uagb-block-ef45d073 .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-buttons .uagb-block-6b122c8e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7749bd8{width: 100%;}.wp-block-uagb-container.uagb-block-c7749bd8{padding-top: 0px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-70fdad5f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-70fdad5f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87120db6{width: 100%;}.wp-block-uagb-container.uagb-block-87120db6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-f108d890 .uagb-heading-text{font-size: 19px;}.uagb-block-7b98e2d8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7b98e2d8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-7b98e2d8 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.uagb-block-7b98e2d8 .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-buttons .uagb-block-82a7c7d0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4feed63b{width: 100%;}.wp-block-uagb-container.uagb-block-4feed63b{padding-top: 0px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-24f82c6e.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-24f82c6e.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3c8740a{width: 100%;}.wp-block-uagb-container.uagb-block-e3c8740a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-0f972975 .uagb-heading-text{font-size: 19px;}.uagb-block-e34e939f.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-e34e939f.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-e34e939f .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.uagb-block-e34e939f .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-buttons .uagb-block-daacf913.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbd51cf9{width: 100%;}.wp-block-uagb-container.uagb-block-bbd51cf9{padding-top: 0px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-0f51fa3f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-0f51fa3f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-55629b35{width: 100%;}.wp-block-uagb-container.uagb-block-55629b35{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-ae112029 .uagb-heading-text{font-size: 19px;}.uagb-block-7685bf4e.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7685bf4e.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-7685bf4e .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.uagb-block-7685bf4e .uagb-buttons-repeater.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-buttons .uagb-block-ab0e37e7.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d51cf7e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d51cf7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5d51cf7e{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7482085c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-7482085c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 20px;padding-bottom: 20px;padding-left: 20px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-7482085c .uagb-infobox-cta-link{border-style: solid;border-color: var(--ast-global-color-8);}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d11e51c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d11e51c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9d11e51c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(0deg, #06558a 0%, #0063A1 100%);;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f407804{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f407804 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6f407804{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 120px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2aa54d97{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2aa54d97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2aa54d97{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-9a935cfd.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-9a935cfd .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-9a935cfd .uagb-cta__wrap{text-align: center;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #ffffff;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #ffffff;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-adbeb591{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-adbeb591{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(90deg,rgb(4,50,99) 0%,rgb(35,158,254) 100%);;background-clip: padding-box;align-items: stretch;flex-wrap: wrap;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ea1e98f0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ea1e98f0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-ea1e98f0 .uagb-ifb-title{font-size: 22px;}.uagb-block-ea1e98f0 .uagb-ifb-title-prefix{font-size: 16px;line-height: 1.7em;}[dir=rtl] .uagb-block-ea1e98f0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87b1688c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-87b1688c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-87b1688c{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4c9e5cab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4c9e5cab .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-bottom: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-bottom: 20px;}.uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4c9e5cab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5485eaf5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5485eaf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5485eaf5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf8027fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-bf8027fe{padding-top: 0px;padding-bottom: 24px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-5f377dc0.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-5f377dc0.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-319b90fd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-319b90fd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.uagb-block-03239280.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-9c4a6211 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-8a34de35 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-f65e2216 .uagb-heading-text{font-size: 19px;}.uagb-block-ef45d073.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-ef45d073.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-6b122c8e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-6b122c8e .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7749bd8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c7749bd8{padding-top: 0px;padding-bottom: 24px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-70fdad5f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-70fdad5f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-87120db6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-87120db6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.uagb-block-c83684c0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-c273a7f6 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-c83511e9 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-f108d890 .uagb-heading-text{font-size: 19px;}.uagb-block-7b98e2d8.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7b98e2d8.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-82a7c7d0.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-82a7c7d0 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4feed63b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-4feed63b{padding-top: 0px;padding-bottom: 24px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-24f82c6e.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-24f82c6e.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3c8740a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e3c8740a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.uagb-block-a8c24aea.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-50c94fe3 .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-6e8af511 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-0f972975 .uagb-heading-text{font-size: 19px;}.uagb-block-e34e939f.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-e34e939f.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-daacf913.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-daacf913 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bbd51cf9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-bbd51cf9{padding-top: 0px;padding-bottom: 24px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-0f51fa3f.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-0f51fa3f.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-55629b35{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-55629b35{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-alternate-background);background: linear-gradient(90deg,rgba(227,227,227,0.5) 0%,rgba(167,186,210,0.5) 100%);;background-clip: padding-box;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.uagb-block-42779a31.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-5f89b45a .uagb-heading-text{font-size: 18px;}.wp-block-uagb-advanced-heading.uagb-block-5c5faaf8 .uagb-heading-text{font-size: 17px;}.wp-block-uagb-advanced-heading.uagb-block-ae112029 .uagb-heading-text{font-size: 19px;}.uagb-block-7685bf4e.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-7685bf4e.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-ab0e37e7.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-ab0e37e7 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d51cf7e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d51cf7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5d51cf7e{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7482085c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7482085c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7482085c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-bottom: 20px;}.uagb-block-7482085c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-bottom: 20px;}.uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 12px;}.uagb-block-7482085c .uagb-infobox-cta-link{border-style: solid;border-color: var(--ast-global-color-8);}[dir=rtl] .uagb-block-7482085c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 12px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d11e51c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d11e51c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9d11e51c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(0deg, #06558a 0%, #0063A1 100%);;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6f407804{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6f407804 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6f407804{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-716f4730.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 120px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2aa54d97{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2aa54d97 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2aa54d97{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-9a935cfd.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-9a935cfd .uagb-cta__buttons{justify-content: center;}.uagb-block-9a935cfd .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-9a935cfd .uagb-cta__wrap{text-align: center;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #ffffff;}.uagb-block-9a935cfd.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #ffffff;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:458:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-6b122c8e' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-82a7c7d0' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-daacf913' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-ab0e37e7' );\n});\n });\";s:18:\"current_block_list\";a:17:{i:0;s:14:\"uagb\/container\";i:1;s:13:\"uagb\/info-box\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:10:\"core\/group\";i:5;s:17:\"uagb\/loop-builder\";i:7;s:17:\"uagb\/loop-wrapper\";i:9;s:10:\"uagb\/image\";i:10;s:12:\"uagb\/buttons\";i:11;s:18:\"uagb\/buttons-child\";i:13;s:25:\"uagb\/animations-extension\";i:15;s:19:\"uagb\/call-to-action\";i:16;s:11:\"core\/search\";i:18;s:12:\"core\/heading\";i:19;s:17:\"core\/latest-posts\";i:20;s:20:\"core\/latest-comments\";i:21;s:13:\"core\/archives\";i:22;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778671645\";s:6:\"gfonts\";a:1:{s:10:\"Montserrat\";a:2:{s:10:\"fontfamily\";s:10:\"Montserrat\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"500\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a.webp",1200,675,false],"thumbnail":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a-200x113.webp",200,113,true],"medium":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a-400x225.webp",400,225,true],"medium_large":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a-768x432.webp",768,432,true],"large":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a-800x450.webp",800,450,true],"1536x1536":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a.webp",1200,675,false],"2048x2048":["https:\/\/www.horlyviaggi.it\/viaggi\/wp-content\/uploads\/sites\/2\/2026\/03\/cilento-10a.webp",1200,675,false]},"uagb_author_info":{"display_name":"Orlando Manzi","author_link":"https:\/\/www.horlyviaggi.it\/viaggi\/author\/orlando\/"},"uagb_comment_info":0,"uagb_excerpt":"Agosto 2026","_links":{"self":[{"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/pages\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":5,"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/pages\/4941\/revisions"}],"predecessor-version":[{"id":5272,"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/pages\/4941\/revisions\/5272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/media\/4804"}],"wp:attachment":[{"href":"https:\/\/www.horlyviaggi.it\/viaggi\/wp-json\/wp\/v2\/media?parent=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}